{"id":4608,"date":"2020-10-10T13:14:08","date_gmt":"2020-10-10T11:14:08","guid":{"rendered":"http:\/\/gaq.be\/evenements\/collecte-des-encombrants-4\/"},"modified":"2020-10-10T13:14:08","modified_gmt":"2020-10-10T11:14:08","slug":"collecte-des-encombrants-4","status":"publish","type":"tribe_events","link":"https:\/\/gaq.be\/en\/evenements\/collecte-des-encombrants-4\/","title":{"rendered":"Collecte des Encombrants"},"content":{"rendered":"<p> \/ et: \/ Rue Joseph II (entre Livingstone et Taciturne) \/ Infos: 0800-901 07<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\/ et: \/ Rue Joseph II (entre Livingstone et Taciturne) \/ Infos: 0800-901 07<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Brussels","_EventStartDate":"2018-10-18 00:00:00","_EventEndDate":"2018-10-18 18:00:00","_EventStartDateUTC":"2018-10-17 22:00:00","_EventEndDateUTC":"2018-10-18 16:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4608","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/tribe_events\/4608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/tribe_events\/4608\/revisions"}],"wp:attachment":[{"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/media?parent=4608"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/tags?post=4608"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/gaq.be\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=4608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}