{"id":5246,"date":"2020-10-10T13:18:20","date_gmt":"2020-10-10T11:18:20","guid":{"rendered":"http:\/\/gaq.be\/evenements\/gaq-reunion-publique-14\/"},"modified":"2020-11-18T10:04:11","modified_gmt":"2020-11-18T09:04:11","slug":"gaq-reunion-publique-14","status":"publish","type":"tribe_events","link":"https:\/\/gaq.be\/nl\/evenements\/gaq-reunion-publique-14\/","title":{"rendered":"GAQ r\u00e9union publique"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\tdinsdag 1 december 2020\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t \u00e0 \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t20:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t22:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"Links weergeven om evenementen aan je kalender toe te voegen\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tToevoegen aan kalender\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20201201T200000\/20201201T220000&#038;text=GAQ%20r%C3%A9union%20publique&#038;details=&#038;trp=false&#038;ctz=Europe\/Brussels&#038;sprop=website:https:\/\/gaq.be\/nl\/\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Calendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<div  class=\"tribe-events-single-section tribe-events-event-meta primary tribe-clearfix\" >\n\t\n\t\n<div class=\"tribe-events-meta-group tribe-events-meta-group-details\">\n\t<h3 class=\"tribe-events-single-section-title\">\n\t\t\t\t\tGegevens\t\t\n\t<\/h3>\n\t<ul class=\"tribe-events-meta-list\">\n\n\t\t\n\t\t\t<li class=\"tribe-events-meta-item\">\n\t\t\t\t<span class=\"tribe-events-meta-label\">Datum:<\/span>\n\t\t\t\t<span class=\"tribe-events-meta-value\">\n\t\t\t\t\t<abbr class=\"tribe-events-abbr tribe-events-start-date published dtstart\" title=\"2020-12-01\"> dinsdag 1 december 2020 <\/abbr>\n\t\t\t\t<\/span>\n\t\t\t<\/li>\n\n\t\t\t<li class=\"tribe-events-meta-item\">\n\t\t\t\t<span class=\"tribe-events-meta-label\">Tijd:<\/span>\n\t\t\t\t<span class=\"tribe-events-meta-value\">\n\t\t\t\t\t<div class=\"tribe-events-abbr tribe-events-start-time published dtstart\" title=\"2020-12-01\">\n\t\t\t\t\t\t20:00 &#8211; 22:00\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/span>\n\t\t\t<\/li>\n\n\t\t\n\t\t\n\t\t\n\t\t<li class=\"tribe-events-meta-item\"><span class=\"tribe-events-event-categories-label tribe-events-meta-label\">Evenement Categorie:<\/span> <span class=\"tribe-events-event-categories tribe-events-meta-value\"><a href=\"https:\/\/gaq.be\/agenda\/category\/rm-reunion-mensuelle\/\" rel=\"tag\">RM R\u00e9union Mensuelle<\/a><\/span><\/li>\n\t\t\n\t\t\n\t\t\t<\/ul>\n<\/div>\n\t\n<div class=\"tribe-events-meta-group tribe-events-meta-group-organizer\">\n\t<h3 class=\"tribe-events-single-section-title\">\n\t\t\t\t\tOrganisator\t\t\t<\/h3>\n\t<ul class=\"tribe-events-meta-list tribe-events-meta-list-organizer\">\n\t\t\t\t\t<li class=\"tribe-events-meta-item\">\n\t\t\t\t<span class=\"tribe-organizer tribe-events-meta-value\">\n\t\t\t\t\tGAQ\t\t\t\t<\/span>\n\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<\/div>\n\n\t<\/div>\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Brussels","_EventStartDate":"2020-12-01 20:00:00","_EventEndDate":"2020-12-01 22:00:00","_EventStartDateUTC":"2020-12-01 19:00:00","_EventEndDateUTC":"2020-12-01 21:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[844],"_EventVenueID":[0],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[14],"class_list":["post-5246","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-rm-reunion-mensuelle","cat_rm-reunion-mensuelle"],"_links":{"self":[{"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tribe_events\/5246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tribe_events\/5246\/revisions"}],"predecessor-version":[{"id":5806,"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tribe_events\/5246\/revisions\/5806"}],"wp:attachment":[{"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/media?parent=5246"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tags?post=5246"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/gaq.be\/nl\/wp-json\/wp\/v2\/tribe_events_cat?post=5246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}